{"id":11290,"date":"2015-06-07T10:46:03","date_gmt":"2015-06-07T10:46:03","guid":{"rendered":"https:\/\/blog.donottrack-doc.com\/?p=11290"},"modified":"2015-06-07T10:46:03","modified_gmt":"2015-06-07T10:46:03","slug":"que-sait-on-de-moi-quand-je-prends-lavion-de-plus-en-plus-de-choses","status":"publish","type":"post","link":"https:\/\/blog.donottrack-doc.com\/fr\/que-sait-on-de-moi-quand-je-prends-lavion-de-plus-en-plus-de-choses\/","title":{"rendered":"Que sait-on de moi quand je prends l\u2019avion ? De plus en plus de choses"},"content":{"rendered":"<p>De l\u2019achat du billet d\u2019avion \u00e0 la fin du voyage, de nombreuses donn\u00e9es sont r\u00e9colt\u00e9es par les compagnies. Le projet de \u00ab PNR fran\u00e7ais \u00bb s\u2019appr\u00eate \u00e0 industrialiser les \u00e9changes d\u2019informations avec les autorit\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De l\u2019achat du billet d\u2019avion \u00e0 la fin du voyage, de nombreuses donn\u00e9es sont r\u00e9colt\u00e9es par les compagnies. Le projet de \u00ab PNR fran\u00e7ais \u00bb s\u2019appr\u00eate \u00e0 industrialiser les \u00e9changes d\u2019informations avec les autorit\u00e9s.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[124],"tags":[1009,207],"acf":[],"_links":{"self":[{"href":"https:\/\/blog.donottrack-doc.com\/fr\/wp-json\/wp\/v2\/posts\/11290"}],"collection":[{"href":"https:\/\/blog.donottrack-doc.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.donottrack-doc.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.donottrack-doc.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.donottrack-doc.com\/fr\/wp-json\/wp\/v2\/comments?post=11290"}],"version-history":[{"count":1,"href":"https:\/\/blog.donottrack-doc.com\/fr\/wp-json\/wp\/v2\/posts\/11290\/revisions"}],"predecessor-version":[{"id":11291,"href":"https:\/\/blog.donottrack-doc.com\/fr\/wp-json\/wp\/v2\/posts\/11290\/revisions\/11291"}],"wp:attachment":[{"href":"https:\/\/blog.donottrack-doc.com\/fr\/wp-json\/wp\/v2\/media?parent=11290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.donottrack-doc.com\/fr\/wp-json\/wp\/v2\/categories?post=11290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.donottrack-doc.com\/fr\/wp-json\/wp\/v2\/tags?post=11290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}