{"id":11282,"date":"2015-06-07T10:36:11","date_gmt":"2015-06-07T10:36:11","guid":{"rendered":"https:\/\/blog.donottrack-doc.com\/?p=11282"},"modified":"2015-06-07T10:36:11","modified_gmt":"2015-06-07T10:36:11","slug":"tracking-et-publicite-representent-40-dune-page-web","status":"publish","type":"post","link":"https:\/\/blog.donottrack-doc.com\/fr\/tracking-et-publicite-representent-40-dune-page-web\/","title":{"rendered":"Tracking et publicit\u00e9 repr\u00e9sentent 40% d&rsquo;une page Web"},"content":{"rendered":"<p>Si la publicit\u00e9 est une nuisance visuelle pour beaucoup d\u2019utilisateurs, son impact s\u2019\u00e9tend \u00e9galement aux performances des sites web. C\u2019est en tout cas\u00a0<a title=\"\" href=\"http:\/\/ieee-security.org\/TC\/SPW2015\/W2SP\/papers\/W2SP_2015_submission_32.pdf\" target=\"_blank\">la conclusion \u00e0 laquelle sont parvenus deux chercheurs<\/a>\u00a0qui se sont pench\u00e9s sur l\u2019effet de l\u2019outil de protection d\u00e9ploy\u00e9 par Mozilla dans Firefox sur les performances et la vitesse de chargement des pages web.<\/p>\n<p>En moyenne, le chargement des pages est 44% plus rapide lorsque l\u2019outil de protection anti-tracking est activ\u00e9, avec une r\u00e9duction du volume de donn\u00e9es \u00e0 t\u00e9l\u00e9charger estim\u00e9e \u00e0 39% selon les deux chercheurs.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si la publicit\u00e9 est une nuisance visuelle pour beaucoup d\u2019utilisateurs, son impact s\u2019\u00e9tend \u00e9galement aux performances des sites web. C\u2019est en tout cas\u00a0la conclusion \u00e0 laquelle sont parvenus deux chercheurs\u00a0qui se sont pench\u00e9s sur l\u2019effet de l\u2019outil de protection d\u00e9ploy\u00e9 par Mozilla dans Firefox sur les performances et la vitesse de chargement des pages web. <a class=\"more-link\" href=\"https:\/\/blog.donottrack-doc.com\/fr\/tracking-et-publicite-representent-40-dune-page-web\/\">Read more<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"link","meta":[],"categories":[124],"tags":[215],"acf":[],"_links":{"self":[{"href":"https:\/\/blog.donottrack-doc.com\/fr\/wp-json\/wp\/v2\/posts\/11282"}],"collection":[{"href":"https:\/\/blog.donottrack-doc.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.donottrack-doc.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.donottrack-doc.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.donottrack-doc.com\/fr\/wp-json\/wp\/v2\/comments?post=11282"}],"version-history":[{"count":1,"href":"https:\/\/blog.donottrack-doc.com\/fr\/wp-json\/wp\/v2\/posts\/11282\/revisions"}],"predecessor-version":[{"id":11283,"href":"https:\/\/blog.donottrack-doc.com\/fr\/wp-json\/wp\/v2\/posts\/11282\/revisions\/11283"}],"wp:attachment":[{"href":"https:\/\/blog.donottrack-doc.com\/fr\/wp-json\/wp\/v2\/media?parent=11282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.donottrack-doc.com\/fr\/wp-json\/wp\/v2\/categories?post=11282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.donottrack-doc.com\/fr\/wp-json\/wp\/v2\/tags?post=11282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}